{"id":23979,"date":"2024-04-04T21:20:40","date_gmt":"2024-04-04T21:20:40","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2024\/04\/04\/habitat-investit-40-millions-deuros-dans-le-developpement-de-200-logements\/"},"modified":"2026-02-20T21:52:05","modified_gmt":"2026-02-20T21:52:05","slug":"habitat-investit-40-millions-deuros-dans-le-developpement-de-200-logements","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2024\/04\/04\/habitat-investit-40-millions-deuros-dans-le-developpement-de-200-logements\/","title":{"rendered":"Habitat investit 40 millions d&rsquo;euros dans le d\u00e9veloppement de 200 logements"},"content":{"rendered":"<p><em>Le promoteur de Bain Capital lance des projets \u00e0 S\u00e9ville, Valence et Gran Canaria, o\u00f9 il a acquis des terrains d&rsquo;une superficie totale de 20.500 m2 pour trois d\u00e9veloppements.<\/em><\/p>\n<p>Habitat Inmobiliaria prend son envol. Le promoteur de Bain Capital vient d&rsquo;acqu\u00e9rir trois nouveaux terrains, d&rsquo;une superficie totale d&rsquo;environ 20.500 m2, dans lesquels il investira quarante millions d&rsquo;euros pour d\u00e9velopper pr\u00e8s de 200 logements. <\/p>\n<p>Le promoteur poursuit ainsi sa feuille de route, qui consiste \u00e0 promouvoir le d\u00e9veloppement de nouveaux logements dans toute l&rsquo;Espagne, en se concentrant cette fois sur l&rsquo;Andalousie, la Communaut\u00e9 valencienne et les \u00celes Canaries. <\/p>\n<p>Ainsi, le premier projet sera situ\u00e9 dans la zone d&rsquo;Entren\u00facleos, \u00e0 Dos Hermanas, une municipalit\u00e9 situ\u00e9e pr\u00e8s du centre-ville de S\u00e9ville. Le nouveau projet dans la province de Valence sera situ\u00e9 dans la zone de Mas Camarena \u00e0 B\u00e9tera. Enfin, le nouveau terrain dans les \u00eeles Canaries est situ\u00e9 dans la zone de Puerto Canteras, au nord de la ville.<\/p>\n<p><strong>La premi\u00e8re acquisition d&rsquo;Habitat Inmobiliaria est situ\u00e9e \u00e0 Entren\u00facelos (S\u00e9ville)<\/strong> et impliquera un investissement de plus de vingt millions d&rsquo;euros, qui permettra le d\u00e9veloppement d&rsquo;environ 110 logements. <\/p>\n<p>Cette acquisition repr\u00e9sente le sixi\u00e8me projet d&rsquo;Habitat Inmobiliaria dans la zone d&rsquo;Entren\u00facleos, une zone consolid\u00e9e de la municipalit\u00e9 de Dos Hermanas qui conna\u00eet une forte croissance et qui est l&rsquo;une des zones les plus recherch\u00e9es de la province de S\u00e9ville.<\/p>\n<p><strong>Habitat consacrera 20 millions d&rsquo;euros \u00e0 la construction de 110 logements \u00e0 Entren\u00facleos, \u00e0 S\u00e9ville<\/strong><\/p>\n<p>Le second des terrains acquis par Habitat Inmobiliaria impliquera un investissement total de plus de 10 millions d&rsquo;euros pour la construction <strong>d&rsquo;une trentaine de maisons individuelles dans la zone de Mas Camarena, une zone en expansion de B\u00e9tera, dans la province de Valence<\/strong>. <\/p>\n<p>Habitat Inmobiliaria poss\u00e8de d\u00e9j\u00e0 deux lotissements (Habitat M\u00e1s Camarena et Habitat Torre en Conill) dans cette commune situ\u00e9e \u00e0 10 minutes en voiture de la ville de Valence. <\/p>\n<p>Le nouveau terrain dispose d&rsquo;une surface constructible de plus de 4.000 m2 et de 5.500 m2 de zones communes compos\u00e9es d&rsquo;espaces verts, d&rsquo;une piscine, d&rsquo;un gymnase, etc.<\/p>\n<p><strong>Le troisi\u00e8me terrain acquis par Habitat Inmobiliaria est situ\u00e9 dans la zone de Puerto Canteras, au nord de Las Palmas de Gran Canaria<\/strong>, l&rsquo;une des zones les plus recherch\u00e9es pour vivre. L&rsquo;entreprise investira pr\u00e8s de 10 millions d&rsquo;euros et d\u00e9veloppera quarante nouveaux logements. <\/p>\n<p>Le nouveau projet, d&rsquo;une surface constructible d&rsquo;environ 4.000 m2, s&rsquo;ajoute aux 3 projets actuellement commercialis\u00e9s par la soci\u00e9t\u00e9 \u00e0 Gran Canaria. <\/p>\n<p>La soci\u00e9t\u00e9, pr\u00e9sid\u00e9e par Juan Mar\u00eda Nin et dirig\u00e9e par Jos\u00e9 Carlos Saz, commercialise actuellement plus de 45 projets et environ 4.000 logements dans toute l&rsquo;Espagne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le promoteur de Bain Capital lance des projets \u00e0 S\u00e9ville, Valence et Gran Canaria, o\u00f9 il a acquis des terrains d&rsquo;une superficie totale de 20.500 m2 pour trois d\u00e9veloppements. Habitat Inmobiliaria prend son envol. Le promoteur de Bain Capital vient d&rsquo;acqu\u00e9rir trois nouveaux terrains, d&rsquo;une superficie totale d&rsquo;environ 20.500 m2, dans lesquels il investira quarante [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23981,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-23979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/23979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=23979"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/23979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/23981"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=23979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=23979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=23979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}