{"id":60659,"date":"2024-07-06T19:30:07","date_gmt":"2024-07-06T19:30:07","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2024\/07\/06\/la-possible-alliance-des-groupes-de-presse\/"},"modified":"2026-03-03T22:31:48","modified_gmt":"2026-03-03T22:31:48","slug":"la-possible-alliance-des-groupes-de-presse","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2024\/07\/06\/la-possible-alliance-des-groupes-de-presse\/","title":{"rendered":"La possible alliance des groupes de presse"},"content":{"rendered":"<p style=\"text-align: left\"><strong>Vocento, grand groupe de presse \u00e9crite et audiovisuelle, cherche \u00e0 d\u00e9velopper des collaborations avec d&rsquo;autres m\u00e9dias espagnols pour faire face \u00e0 la chute du march\u00e9 publicitaire.<\/strong><\/p>\n<p> Luis Enriquez, conseiller d\u00e9l\u00e9gu\u00e9 du groupe Vocento (\u00e9diteur d&rsquo;ABC, Qu\u00e9), a rencontr\u00e9 cet \u00e9t\u00e9 Mauricio Casals, pr\u00e9sident du journal La Raz\u00f3n. Plusieurs autres r\u00e9unions sont pr\u00e9vues en septembre avec Antonio Fernandez Galiano, conseiller d\u00e9l\u00e9gu\u00e9 d&rsquo;Unedisa (\u00e9diteur de Marca, El Mundo), et Jos\u00e9 Luis Sainz, pr\u00e9sident du groupe Prisa, leader du secteur. Objectif\u00a0: \u00e9tudier les possibilit\u00e9s de collaboration ou d&rsquo;alliances afin de r\u00e9duire les co\u00fbts et rester comp\u00e9titifs sur le march\u00e9 de la publicit\u00e9. Des sources proches de la direction de Vocento ont confi\u00e9 au journal L&rsquo;Economista qu&rsquo;il n&rsquo;\u00e9tait pas question de vendre ou de fusionner des journaux mais simplement de cr\u00e9er des synergies entre les grands groupes de presse espagnols. L&rsquo;une des pistes \u00e9tudi\u00e9e est de fusionner les r\u00e9gies publicitaires afin de pouvoir r\u00e9duire les co\u00fbts et proposer de meilleurs tarifs aux annonceurs, principale source de financement des m\u00e9dias. Les groupes pourraient \u00e9galement cr\u00e9er une centrale d&rsquo;achat commune pour mutualiser l&rsquo;achat du papier, les frais d&rsquo;impression et la distribution.  <strong>Un secteur en crise<\/strong>  Ce n&rsquo;est pas la premi\u00e8re fois que les groupes de presse cherchent \u00e0 s&rsquo;allier pour r\u00e9duire leurs co\u00fbts. La situation ne cesse cependant de se d\u00e9t\u00e9riorer pour le secteur et les importantes pertes enregistr\u00e9es au premier semestre par l&rsquo;ensemble des m\u00e9dias pourraient, cette fois-ci, acc\u00e9l\u00e9rer le processus. Unedisa pr\u00e9voit en effet de nouveaux licenciements au cours de l&rsquo;automne, tandis que Prisa a pr\u00e9sent\u00e9 hier un plan social qui affectera 140 de ses salari\u00e9s. Selon APM (association des journalistes de Madrid), plus de 3500 employ\u00e9s du secteur ont perdu leur emploi entre juillet 2008 et juillet 2012. Soixante-sept m\u00e9dias ont ferm\u00e9 leurs portes depuis le d\u00e9but de la crise, tandis que 99 autres ont connu un ou plusieurs plans sociaux.  <em>AC<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vocento, grand groupe de presse \u00e9crite et audiovisuelle, cherche \u00e0 d\u00e9velopper des collaborations avec d&rsquo;autres m\u00e9dias espagnols pour faire face \u00e0 la chute du march\u00e9 publicitaire. Luis Enriquez, conseiller d\u00e9l\u00e9gu\u00e9 du groupe Vocento (\u00e9diteur d&rsquo;ABC, Qu\u00e9), a rencontr\u00e9 cet \u00e9t\u00e9 Mauricio Casals, pr\u00e9sident du journal La Raz\u00f3n. Plusieurs autres r\u00e9unions sont pr\u00e9vues en septembre avec [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46789,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-60659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/60659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=60659"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/60659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/46789"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=60659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=60659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=60659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}