{"id":61260,"date":"2024-07-07T17:35:04","date_gmt":"2024-07-07T17:35:04","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2024\/07\/07\/la-location-monte-en-fleche-sur-le-marche-des-bureaux-de-lisbonne-en-2022\/"},"modified":"2026-02-21T00:28:50","modified_gmt":"2026-02-21T00:28:50","slug":"la-location-monte-en-fleche-sur-le-marche-des-bureaux-de-lisbonne-en-2022","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2024\/07\/07\/la-location-monte-en-fleche-sur-le-marche-des-bureaux-de-lisbonne-en-2022\/","title":{"rendered":"La location monte en fl\u00e8che sur le march\u00e9 des bureaux de Lisbonne en 2022"},"content":{"rendered":"<p><em>La capitale portugaise a connu une ann\u00e9e record en 2022 avec la conclusion d&rsquo;op\u00e9rations de location pour 272.000 m\u00e8tres carr\u00e9s, un record absolu. \u00c0 Porto, 58.500 m\u00e8tres carr\u00e9s ont \u00e9t\u00e9 pris en location.<\/em><\/p>\n<p>Le march\u00e9 portugais des bureaux a connu une excellente ann\u00e9e 2022. La demande sur le march\u00e9 de Lisbonne a atteint 272.000 m\u00e8tres carr\u00e9s, le chiffre le plus \u00e9lev\u00e9 jamais enregistr\u00e9, selon un rapport du cabinet de conseil Cbre. \u00ab\u00a0La demande reste forte et nous pr\u00e9voyons qu&rsquo;elle d\u00e9passera \u00e0 nouveau les 200.000 m\u00e8tres carr\u00e9s en 2023\u00a0\u00bb, indique le rapport.<\/p>\n<p><strong>Ce dynamisme a entra\u00een\u00e9 une baisse du taux d&rsquo;occupation de 35 points de base, \u00e0 8,2% fin 2022<\/strong>, sur un stock total de 4,4 millions de m\u00e8tres carr\u00e9s. Il a \u00e9galement stimul\u00e9 les loyers, qui ont augment\u00e9 dans les meilleurs immeubles de la zone <em>prime<\/em> pour atteindre 27 euros par m\u00e8tre carr\u00e9 et par mois, soit 8% de plus qu&rsquo;\u00e0 la fin de l&rsquo;ann\u00e9e 2021.<\/p>\n<p>En revanche, en dehors de la zone <em>prime<\/em>, les prix des loyers ont baiss\u00e9. Ainsi, par exemple, dans le quartier d&rsquo;affaires de Lisbonne, les loyers s&rsquo;\u00e9tablissent \u00e0 21,9 euros par m\u00e8tre carr\u00e9 par mois fin 2022, en baisse de 3%.<\/p>\n<p><strong>Au cours de l&rsquo;ann\u00e9e, des immeubles de bureaux totalisant environ 189.000 m\u00e8tres carr\u00e9s<\/strong> seront mis sur le march\u00e9. La majorit\u00e9 des immeubles seront disponibles \u00e0 partir du second semestre, ce qui favorisera la signature de pr\u00e9-locations et augmentera la pression \u00e0 la hausse sur les loyers, selon l&rsquo;analyse.<\/p>\n<p><strong>A Lisbonne, les loyers <em>prime<\/em> ont augment\u00e9 de 8%, alors que les prix des loyers ont baiss\u00e9 dans le reste des zones<\/strong><\/p>\n<p>A Porto, la demande plac\u00e9e de bureaux en 2022 s&rsquo;est \u00e9lev\u00e9e \u00e0 58.500 m\u00b2, un chiffre similaire \u00e0 celui de 2021, gr\u00e2ce \u00e0 la conclusion de soixante-dix transactions. <strong>Le taux d&rsquo;occupation du parc de bureaux de Porto, qui totalise 1,27 million de m\u00e8tres carr\u00e9s, \u00e9tait de 4,4% \u00e0 la fin de l&rsquo;ann\u00e9e derni\u00e8re.<\/strong><\/p>\n<p>Les loyers des meilleurs immeubles du principal quartier d&rsquo;affaires de la ville sont rest\u00e9s \u00e0 dix-huit euros par m\u00e8tre carr\u00e9 par mois, bien qu&rsquo;ils aient rebondi dans le quartier d&rsquo;affaires de 4% pour atteindre 15,9 euros par m\u00e8tre carr\u00e9 par mois.<\/p>\n<p>\u00ab\u00a0Nous pr\u00e9voyons une bonne ann\u00e9e 2023 sur le march\u00e9 des bureaux de Porto, car au cours des premiers mois de l&rsquo;ann\u00e9e, il y a eu des recherches actives pour 41.350 m\u00e8tres carr\u00e9s\u00a0\u00bb, selon Cbre, qui souligne \u00e9galement que l&rsquo;entr\u00e9e d&rsquo;une nouvelle offre de qualit\u00e9 augmentera le prix des loyers.<\/p>\n<p>En ce qui concerne le march\u00e9 de l&rsquo;investissement, tant Lisbonne que Porto sont de petites villes. <strong>Le rendement dans le cas de la capitale portugaise s&rsquo;\u00e9levait \u00e0 4,5% fin 2022, soit un demi-point de plus qu&rsquo;en 2021. <\/strong>Le rendement \u00e0 Porto a augment\u00e9 de 25 points de base pour atteindre 6%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La capitale portugaise a connu une ann\u00e9e record en 2022 avec la conclusion d&rsquo;op\u00e9rations de location pour 272.000 m\u00e8tres carr\u00e9s, un record absolu. \u00c0 Porto, 58.500 m\u00e8tres carr\u00e9s ont \u00e9t\u00e9 pris en location. Le march\u00e9 portugais des bureaux a connu une excellente ann\u00e9e 2022. La demande sur le march\u00e9 de Lisbonne a atteint 272.000 m\u00e8tres [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":24223,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-61260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=61260"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/24223"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=61260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=61260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=61260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}