{"id":61471,"date":"2024-07-09T19:25:34","date_gmt":"2024-07-09T19:25:34","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2024\/07\/09\/pertes-historiques-dorange-espagne-moins-52-000-lignes-en-fevrier\/"},"modified":"2026-02-27T01:58:35","modified_gmt":"2026-02-27T01:58:35","slug":"pertes-historiques-dorange-espagne-moins-52-000-lignes-en-fevrier","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2024\/07\/09\/pertes-historiques-dorange-espagne-moins-52-000-lignes-en-fevrier\/","title":{"rendered":"Pertes historiques d&rsquo;Orange Espagne : moins 52 000 lignes en f\u00e9vrier"},"content":{"rendered":"<p class=\"long\">Les d\u00e9parts de clients chez les principaux op\u00e9rateurs mobiles espagnols continuent et s\u2019accumulent. En f\u00e9vrier, selon les chiffres publi\u00e9s par le site internet movilonia.com, Orange, Vodafone, et Movistar r\u00e9unis\u00a0ont perdu plus de 122 000 lignes.<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">L<\/span>a hausse des prix d\u2019abonnements de plusieurs op\u00e9rateurs t\u00e9l\u00e9phoniques, au d\u00e9but de l\u2019ann\u00e9e, ne les aura pas aid\u00e9es \u00e0 conserver leurs clients. En effet, si l\u2019on r\u00e9unit les trois principaux fournisseurs d\u2019acc\u00e8s, la perte s\u2019\u00e9l\u00e8ve \u00e0 122 800 lignes.<\/p>\n<p>De fa\u00e7on plus d\u00e9taill\u00e9e, c\u2019est Orange qui a vu partir le plus de clients en f\u00e9vrier, ils sont ainsi 54 700 \u00e0 avoir rompu leur contrat. Vodafone avec 52 500 lignes perdues et Movistar avec 15 600, sont les deux autres perdants de ce d\u00e9but d\u2019ann\u00e9e.<\/p>\n<p><strong>Les marques moins ch\u00e8res privil\u00e9gi\u00e9es<\/strong><\/p>\n<p>Si les op\u00e9rateurs historiques connaissent des difficult\u00e9s, \u00e7a n\u2019est pas le cas des marques \u00e0 bas prix. Ces derni\u00e8res ont, au contraire, gagn\u00e9 des clients en f\u00e9vrier, au total 81 000. Les ouvertures de lignes ont \u00e9t\u00e9 les plus importantes chez Masm\u00f3vil (33 600 lignes) et chez Yoigo (32 800), toujours selon movilonia.com.<\/p>\n<p>Un l\u00e9ger r\u00e9confort pour les grands op\u00e9rateurs, leurs marques low-cost ont permis de r\u00e9duire les pertes, sans toutefois compenser. Ainsi, pour Orange, ses filiales Jazztel et Simyo ont cl\u00f4tur\u00e9 f\u00e9vrier en ajoutant 6 800 et 4 400 num\u00e9ros, respectivement. Chez Vodafone, c\u2019est la marque Lowi qui permet de compenser les pertes avec l\u2019ouverture de 6 800 lignes.<\/p>\n<p><a href=\"https:\/\/lecourrier.es\/wp-content\/uploads\/2018\/04\/Movilonia-pertes-operateurs-fevrier.png\"><img decoding=\"async\" src=\"https:\/\/yo.estate\/wp-content\/uploads\/2024\/04\/Movilonia-pertes-operateurs-fevrier.png\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les d\u00e9parts de clients chez les principaux op\u00e9rateurs mobiles espagnols continuent et s\u2019accumulent. En f\u00e9vrier, selon les chiffres publi\u00e9s par le site internet movilonia.com, Orange, Vodafone, et Movistar r\u00e9unis\u00a0ont perdu plus de 122 000 lignes. La hausse des prix d\u2019abonnements de plusieurs op\u00e9rateurs t\u00e9l\u00e9phoniques, au d\u00e9but de l\u2019ann\u00e9e, ne les aura pas aid\u00e9es \u00e0 conserver [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":38355,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-61471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=61471"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/38355"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=61471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=61471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=61471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}