{"id":61478,"date":"2024-07-09T20:00:27","date_gmt":"2024-07-09T20:00:27","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2024\/07\/09\/les-compagnies-aeriennes-asiatiques-tournent-leurs-regards-vers-seville\/"},"modified":"2026-02-27T03:48:20","modified_gmt":"2026-02-27T03:48:20","slug":"les-compagnies-aeriennes-asiatiques-tournent-leurs-regards-vers-seville","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2024\/07\/09\/les-compagnies-aeriennes-asiatiques-tournent-leurs-regards-vers-seville\/","title":{"rendered":"Les compagnies a\u00e9riennes asiatiques tournent leurs regards vers S\u00e9ville"},"content":{"rendered":"<p class=\"long\"><span class=\"times-dropcap\">S<\/span>\u00e9ville accueillera les 8 et 9 octobre le congr\u00e8s Global Summit CAPA Low Cost Long-Haul, un \u00e9v\u00e9nement de compagnies a\u00e9riennes low-cost op\u00e9rant \u00a0sur les long-courriers et sp\u00e9cialis\u00e9es sur le march\u00e9 asiatique. Ce sera la premi\u00e8re fois que cette r\u00e9union aura lieu en dehors de l\u2019Asie.<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">I<\/span>l s\u2019agit d\u2019un congr\u00e8s international de la plus haute importance pour lequel le Consortium du tourisme de S\u00e9ville a travaill\u00e9 intens\u00e9ment\u00a0\u00bb, a expliqu\u00e9 Amgel Mu\u00f1oz, d\u00e9l\u00e9gu\u00e9 du D\u00e9partement de l\u2019habitat urbain, de la culture et du tourisme de la ville de S\u00e9ville. Le congr\u00e8s a \u00e9galement le soutien de la Junta de Andalucia, de Turespa\u00f1a, de l\u2019AENA et de l\u2019a\u00e9roport San Pablo.<\/p>\n<p>En fait, \u00ab\u00a0ce sommet tentera de renforcer la connectivit\u00e9 a\u00e9rienne de San Pablo avec toute la zone Asie-Pacifique\u00a0\u00bb, selon des sources de la municipalit\u00e9, soit en ouvrant des routes directes, soit en passant par des plaques tournantes europ\u00e9ennes.<\/p>\n<p>\u00ab\u00a0Pour la strat\u00e9gie du tourisme de la ville, il est prioritaire d\u2019intensifier les actions avec ces march\u00e9s \u00e9loign\u00e9s, car ils contribuent \u00e0 un tourisme de meilleure qualit\u00e9, avec plus de s\u00e9jour et de d\u00e9penses\u00a0\u00bb, a d\u00e9clar\u00e9 M. Mu\u00f1oz.<\/p>\n<p>L\u2019a\u00e9roport de S\u00e9ville a enregistr\u00e9 5,10 millions de passagers l\u2019ann\u00e9e derni\u00e8re, soit 10,5% de plus, et vingt nouvelles routes ont \u00e9t\u00e9 ouvertes.<\/p>\n<p><strong>Nouvelles tendances en mati\u00e8re de low-cost sur de longues distances<\/strong><\/p>\n<p>Selon Corine Hitching, responsable mondial des \u00e9v\u00e9nements au Centre pour l\u2019aviation Asie-Pacifique de la CAPA, les nouvelles technologies appliqu\u00e9es aux avions, l\u2019\u00e9volution des pr\u00e9f\u00e9rences des passagers et la stabilit\u00e9 des prix du carburans facilitent l\u2019\u00e9mergence du low-cost sur le march\u00e9 des longues distances, particuli\u00e8rement en Asie, en Am\u00e9rique du Nord et en Am\u00e9rique latine.<\/p>\n<p>\u00ab\u00a0Dans ce cadre, les a\u00e9roports secondaires, tels que San Pablo, sont des cibles constantes pour les compagnies low-cost, ce qui ouvre de nouvelles opportunit\u00e9s d\u2019op\u00e9rer avec des pays long-courriers\u00a0\u00bb, a d\u00e9clar\u00e9 Corinne Hitching.<\/p>\n<p><strong>Profil de voyageurs<\/strong><\/p>\n<p>\u00ab\u00a0Le low-cost ne signifie pas une qualit\u00e9 m\u00e9diocre. Dans ce nouveau cadre, les termes sont \u00e9galement modifi\u00e9s. Avec ces march\u00e9s longues distances, nous recherchons un tourisme de qualit\u00e9, car les voyageurs de pays lointains sont caract\u00e9ris\u00e9s par plus de s\u00e9jours et des d\u00e9penses moyennes plus \u00e9lev\u00e9es que la moyenne et, par cons\u00e9quent, g\u00e9n\u00e8rent \u00e9galement plus de revenus pour l\u2019ensemble du secteur\u00a0\u00bb, a soutenu Angel Mu\u00f1oz.<\/p>\n<p>\u00ab\u00a0Cela peut \u00eatre jusqu\u2019\u00e0 sept fois plus\u00a0\u00bb, a ajout\u00e9 Manuel Butler, directeur de Turespa\u00f1a, qui a soulign\u00e9 l\u2019importance de cet \u00e9v\u00e9nement international dans l\u2019engagement pris par le minist\u00e8re de l\u2019Industrie, de l\u2019Energie et du num\u00e9rique pour un \u00ab\u00a0tourisme de qualit\u00e9, qui \u00e0 son tour apporte plus de rentabilit\u00e9 \u00e0 l\u2019ensemble des entreprises et \u00e0 l\u2019emploi, et pour la diversification des march\u00e9s, en plus d\u2019avoir lieu \u00e0 un moment de changement technologique\u00a0: l\u2019\u00e9mergence de compagnies a\u00e9riennes low-cost et long-courriers.\u00a0\u00bb<\/p>\n<p><strong>Centres de maintenance d\u2019avions<\/strong><\/p>\n<p>\u00ab\u00a0Ce congr\u00e8s est une formidable opportunit\u00e9 pour le secteur a\u00e9rospatial andalou. Cela nous permettra d\u2019offrir aux compagnies a\u00e9riennes qui assisteront au sommet, une vision de l\u2019Andalousie et de S\u00e9ville comme une escale strat\u00e9gique pour leurs vols long-courriers, comme l\u2019a fait Ryanair, qui a annonc\u00e9 sa d\u00e9cision d\u2019implanter \u00e0 S\u00e9ville son centre de maintenance pour les avions op\u00e9rant dans le sud de l\u2019Europe\u00a0\u00bb, a d\u00e9clar\u00e9 Julio Coca Blanes, directeur g\u00e9n\u00e9ral de l\u2019Agence IDEA de la Junta de Andalucia.<\/p>\n<p>Actuellement, a ajout\u00e9 Julio Coca, la maintenance a\u00e9ronautique repr\u00e9sente 20 % du chiffre d\u2019affaires total du secteur a\u00e9ronautique en Andalousie, soit pr\u00e8s de 500 millions d\u2019euros.<\/p>\n<p>\u00ab\u00a0En effet, la r\u00e9union d\u2019octobre sera \u00e9galement l\u2019occasion pour les compagnies a\u00e9riennes de s\u2019informer sur le tissu d\u2019affaires de l\u2019a\u00e9ronautique de S\u00e9ville avant une nouvelle niche de march\u00e9 qui s\u2019ouvre \u00e0 l\u2019industrie a\u00e9rospatiale\u00a0: la r\u00e9paration et la maintenance des avions.\u00a0\u00bb, a ajout\u00e9 Antonio Mu\u00f1oz.<\/p>\n<p>\u00c0 cet \u00e9gard, il a rappel\u00e9 que S\u00e9ville assumera la pr\u00e9sidence du r\u00e9seau des villes Ariane et sera, alors, la capitale europ\u00e9enne du secteur a\u00e9rospatial en 2019, tout en remerciant l\u2019implication de l\u2019industrie a\u00e9ronautique s\u00e9villane dans l\u2019\u00e9v\u00e9nement CAPA \u00e0 travers la Fondation Helix, la Fondation FADA et le Centre des technologies a\u00e9rospatiales de CATEC.<\/p>\n<p><strong>Croissance mondiale<\/strong><\/p>\n<p>Pour sa part, le directeur de l\u2019a\u00e9roport de S\u00e9ville, Jes\u00fas Caballero, a indiqu\u00e9 que les pr\u00e9visions indiquent que le trafic a\u00e9rien international doublera dans le monde d\u2019ici une quinzaine d\u2019ann\u00e9es et qu\u2019il y aura donc une forte demande pour les nouveaux avions et entretien et r\u00e9paration de ceux-ci.<\/p>\n<p>D\u2019o\u00f9 les \u00ab\u00a0grandes opportunit\u00e9s qui se pr\u00e9sentent \u00e0 l\u2019industrie a\u00e9ronautique. Sur le terrain du tourisme, S\u00e9ville et l\u2019Espagne doivent profiter de leur emplacement strat\u00e9gique, \u00e0 mi-chemin entre l\u2019Am\u00e9rique et l\u2019Asie.\u00a0\u00bb<\/p>\n<p><strong>Rencontres et pr\u00e9sentations<\/strong><\/p>\n<p>Pendant le congr\u00e8s, des r\u00e9unions auront lieu entre les dirigeants et les cadres sup\u00e9rieurs des compagnies a\u00e9riennes, des soci\u00e9t\u00e9s de tourisme (tels que les cha\u00eenes h\u00f4teli\u00e8res, les agences de voyages, les voyagistes, etc.) et les a\u00e9roports.<\/p>\n<p>Des pr\u00e9sentations seront \u00e9galement faites sur les principaux op\u00e9rateurs et panels de services interurbains avec des questions telles que le r\u00f4le des filiales longue distance \u00e0 faible co\u00fbt, la faisabilit\u00e9 de transporteurs interurbains ind\u00e9pendants \u00e0 bas prix face \u00e0 de grands groupes, l\u2019\u00e9volution des relations des compagnies a\u00e9riennes avec les a\u00e9roports, etc.<\/p>\n<p>On estime qu\u2019il y aura une trentaine de compagnies a\u00e9riennes et, au moins, 250 d\u00e9l\u00e9gu\u00e9s de diff\u00e9rents secteurs du tourisme.<\/p>\n<p>Source : <a href=\"https:\/\/www.hosteltur.com\/126753_aerolineas-asiaticas-fijan-su-mirada-sevilla.html\" target=\"_blank\" rel=\"noopener\">hosteltur.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e9ville accueillera les 8 et 9 octobre le congr\u00e8s Global Summit CAPA Low Cost Long-Haul, un \u00e9v\u00e9nement de compagnies a\u00e9riennes low-cost op\u00e9rant \u00a0sur les long-courriers et sp\u00e9cialis\u00e9es sur le march\u00e9 asiatique. Ce sera la premi\u00e8re fois que cette r\u00e9union aura lieu en dehors de l\u2019Asie. Il s\u2019agit d\u2019un congr\u00e8s international de la plus haute importance [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":38525,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[2606,2607,1941,2608,332,628,513],"class_list":["post-61478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-aeroports-de-seville","tag-asie","tag-compagnie-low-cost","tag-compagnies-aeriennes-asiatiques","tag-espagne","tag-seville","tag-tourisme-espagne"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=61478"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/38525"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=61478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=61478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=61478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}