{"id":61485,"date":"2024-07-09T20:20:24","date_gmt":"2024-07-09T20:20:24","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2024\/07\/09\/la-villa-mexicaine-de-pablo-escobar-transformee-en-hotel-de-luxe\/"},"modified":"2026-02-27T04:35:30","modified_gmt":"2026-02-27T04:35:30","slug":"la-villa-mexicaine-de-pablo-escobar-transformee-en-hotel-de-luxe","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2024\/07\/09\/la-villa-mexicaine-de-pablo-escobar-transformee-en-hotel-de-luxe\/","title":{"rendered":"La villa mexicaine de Pablo Escobar transform\u00e9e en h\u00f4tel de luxe"},"content":{"rendered":"<p class=\"long\">Les nombreuses villas du baron de la drogue Pablo Escobar ne se sont pas limit\u00e9es \u00e0 son pays d\u2019origine. L\u2019une d\u2019entre elles a \u00e9t\u00e9 d\u00e9couverte en 2003, et depuis, transform\u00e9e en h\u00f4tel de luxe.<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">C<\/span>\u2019est \u00e0 Tulum (M\u00e9xico) que Pablo Escobar a fait construire une villa, face \u00e0 la plage, sur un terrain entour\u00e9 par la jungle. La propri\u00e9t\u00e9 est constitu\u00e9e d\u2019un b\u00e2timent principal et d\u2019autres, plus petits, autour.<\/p>\n<p>\u00c0 la mort du Colombien, en 1993, ses biens sont abandonn\u00e9s ou saisis. C\u2019est en 2003 que la villa de Tulum est d\u00e9couverte, et en 2013 que le marchand d\u2019art Lio Malca l\u2019ach\u00e8te. Apr\u00e8s une r\u00e9novation totale, la villa est transform\u00e9e en un des h\u00f4tels les plus luxueux au monde.<\/p>\n<p>Nomm\u00e9 Casa Malca, l\u2019h\u00f4tel compte 36 chambres et est d\u00e9cor\u00e9 avec la collection d\u2019\u0153uvres d\u2019art personnelle de Lio Malca. Ainsi, des pi\u00e8ces contemporaines de Kenny Scharf ou des peintures de Marion Peck ornent les couloirs et les murs des b\u00e2timents.<\/p>\n<p>Fr\u00e9quent\u00e9 par certaines c\u00e9l\u00e9brit\u00e9s, dont Leonardo Di Caprio, une nuit \u00e0 l\u2019h\u00f4tel Casa Malca vous co\u00fbtera en moyenne 500 euros.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/yo.estate\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-193.jpg\"><\/p>\n<p>Photos : www.casamalca.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les nombreuses villas du baron de la drogue Pablo Escobar ne se sont pas limit\u00e9es \u00e0 son pays d\u2019origine. L\u2019une d\u2019entre elles a \u00e9t\u00e9 d\u00e9couverte en 2003, et depuis, transform\u00e9e en h\u00f4tel de luxe. C\u2019est \u00e0 Tulum (M\u00e9xico) que Pablo Escobar a fait construire une villa, face \u00e0 la plage, sur un terrain entour\u00e9 par [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":38599,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[781,2628],"class_list":["post-61485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-hotel-de-luxe","tag-pablo-escobar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=61485"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/38599"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=61485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=61485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=61485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}