{"id":61552,"date":"2024-07-10T03:35:13","date_gmt":"2024-07-10T03:35:13","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2024\/07\/10\/le-fondateur-de-pokerstars-investit-225-millions-dans-un-complexe-proche-de-sol-et-gran-via\/"},"modified":"2026-02-28T03:10:50","modified_gmt":"2026-02-28T03:10:50","slug":"le-fondateur-de-pokerstars-investit-225-millions-dans-un-complexe-proche-de-sol-et-gran-via","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2024\/07\/10\/le-fondateur-de-pokerstars-investit-225-millions-dans-un-complexe-proche-de-sol-et-gran-via\/","title":{"rendered":"Le fondateur de PokerStars investit 225 millions dans un complexe proche de Sol et Gran Via"},"content":{"rendered":"<p style=\"text-align: justify\">A deux pas de Sol et de Gran Via, le complexe immobilier le plus luxueux de Madrid vient d&rsquo;\u00eatre rachet\u00e9 ! Si l&rsquo;investisseur colombien\u00a0<a href=\"https:\/\/lecourrier.es\/un-colombien-va-racheter-le-complexe-immobilier-le-plus-luxueux-de-madrid\/\">Jaime Gilinski \u00e9tait initialement pressenti pour racheter le complexe Canalejas<\/a>, c&rsquo;est finalement\u00a0Mark Scheinberg, co-fondateur de la plateforme de jeux en ligne PokerStars et dont la fortune est \u00e9valu\u00e9e \u00e0 plus de 4 milliards d&rsquo;euros, qui a fait l&rsquo;acquisition du bien pour 225 millions d&rsquo;euros.<\/p>\n<p style=\"text-align: justify\">Lanc\u00e9e en septembre dernier, l&rsquo;op\u00e9ration avait suscit\u00e9 l&rsquo;int\u00e9r\u00eat de nombreux investisseurs. Mark Scheinberg, qui poss\u00e8de la double nationalit\u00e9 isra\u00e9lienne et canadienne, a fini par s&rsquo;imposer face \u00e0 la concurrence et a rachet\u00e9 le luxueux complexe au groupe Villar Mir qui le d\u00e9tenait depuis 2013.<\/p>\n<p style=\"text-align: justify\">Un accord a \u00e9t\u00e9 conclu afin que OHL Desarrollos et Villar Mir vendent des actions \u00e0 la soci\u00e9t\u00e9 Mohari Limited, dirig\u00e9e par\u00a0Mark Scheinberg.<\/p>\n<p style=\"text-align: justify\">L&rsquo;homme d&rsquo;affaires a d\u00e9bours\u00e9 225 millions d&rsquo;euros pour poss\u00e9der 50 % du bien immobilier.\u00a0OHL Desarrollos et le groupe Villar Mir, qui poss\u00e8dent respectivement une part de 17,5% et de 32,5% du complexe de luxe, continueront de s&rsquo;occuper de sa gestion jusqu&rsquo;\u00e0\u00a0l&rsquo;inauguration du projet pr\u00e9vue pour 2018.<\/p>\n<p style=\"text-align: justify\">Un h\u00f4tel de luxe g\u00e9r\u00e9 par le Four Seasons devrait voir le jour, ainsi qu&rsquo;un centre commercial de 15 000 m2 et un parking pouvant accueillir jusqu&rsquo;\u00e0 500 places. Il est situ\u00e9 \u00e0 deux pas de Sol et de Gran Via.<\/p>\n<p style=\"text-align: justify\">Cr\u00e9dits photo : OHL Desarrollos<\/p>\n<p style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>A deux pas de Sol et de Gran Via, le complexe immobilier le plus luxueux de Madrid vient d&rsquo;\u00eatre rachet\u00e9 ! Si l&rsquo;investisseur colombien\u00a0Jaime Gilinski \u00e9tait initialement pressenti pour racheter le complexe Canalejas, c&rsquo;est finalement\u00a0Mark Scheinberg, co-fondateur de la plateforme de jeux en ligne PokerStars et dont la fortune est \u00e9valu\u00e9e \u00e0 plus de 4 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":40399,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[1787,362,2773],"class_list":["post-61552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-complejo-canalejas","tag-immobilier-espagne","tag-pokerstars"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=61552"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/61552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/40399"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=61552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=61552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=61552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}