{"id":70595,"date":"2026-03-11T05:49:20","date_gmt":"2026-03-11T05:49:20","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2026\/03\/11\/le-siege-de-wework-en-vente-a-chamberi-premiere-grande-transaction-de-bureaux-de-2024-2\/"},"modified":"2026-05-07T13:15:21","modified_gmt":"2026-05-07T13:15:21","slug":"le-siege-de-wework-en-vente-a-chamberi-premiere-grande-transaction-de-bureaux-de-2024-2","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2026\/03\/11\/le-siege-de-wework-en-vente-a-chamberi-premiere-grande-transaction-de-bureaux-de-2024-2\/","title":{"rendered":"Le si\u00e8ge de WeWork en vente \u00e0 Chamber\u00ed, premi\u00e8re grande transaction de bureaux de 2024"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p><em>Swiss Life vient de lancer la 1<sup>re<\/sup> grande transaction de bureaux de l&#8217;ann\u00e9e, la vente de l&#8217;immeuble situ\u00e9 au 27 rue Eloy Gonzalo, si\u00e8ge de la soci\u00e9t\u00e9 de location de bureaux flexibles WeWork \u00e0 Chamber\u00ed.<\/em><\/p>\n<p>WeWork continue de supprimer des postes. La soci\u00e9t\u00e9 new-yorkaise de location de bureaux flexibles, autrefois \u00e9valu\u00e9e \u00e0 50 milliards de dollars, a d\u00e9pos\u00e9 son bilan en novembre dernier car elle ne pouvait plus faire face \u00e0 sa dette de 18,6 milliards de dollars. Aujourd&#8217;hui, selon El Confidencial, <strong>Swiss Life a mis en vente son centre de bureaux de 6.000 m2 \u00e0 Chamber\u00ed (Madrid)<\/strong>.<\/p>\n<p>L&#8217;annonce de la vente de Swiss Life constitue la 1<sup>re<\/sup> grande transaction de bureaux de l&#8217;ann\u00e9e 2024. L&#8217;actif, situ\u00e9 au num\u00e9ro 27 de la Calle Eloy Gonzalo, au centre du quartier madril\u00e8ne de Chamber\u00ed, est lou\u00e9 par WeWork, qui poss\u00e8de la quasi-totalit\u00e9 des 6.327m2. En effet, le g\u00e9ant new-yorkais du coworking occupe tous les \u00e9tages de l&#8217;immeuble, \u00e0 l&#8217;exception du rez-de-chauss\u00e9e et du 7<sup>\u00e8me<\/sup>.<\/p>\n<p>La compagnie d&#8217;assurance suisse Swiss Life a acquis ce b\u00e2timent aupr\u00e8s du Grupo Lar il y a 4 ans pour une 40aine de millions d&#8217;euros. Cependant, elle souhaite aujourd&#8217;hui s&#8217;en d\u00e9faire dans le but de d\u00e9passer le montant pour lequel elle a achet\u00e9 l&#8217;actif.<\/p>\n<p>WeWork n&#8217;est pas dans une situation facile, car l&#8217;arriv\u00e9e du t\u00e9l\u00e9travail et l&#8217;augmentation du ch\u00f4mage en provenance des Etats-Unis repr\u00e9sentent la situation du march\u00e9 dans cette cession importante.<\/p>\n<h3 class=\"wp-block-heading\"><strong>En novembre 2023, les actions de WeWork ont plong\u00e9 de plus de 50% pour atteindre 1,10$ par action<\/strong><\/h3>\n<p>Le groupe propose 660 espaces \u00e0 louer dans 37 pays et compte 100.000 cr\u00e9anciers. Le plus grand cr\u00e9ancier de WeWork est US Bank Trust, avec une dette d&#8217;un peu plus de 180 millions de dollars.<\/p>\n<p>Lors de la pr\u00e9sentation de ses r\u00e9sultats semestriels en juillet dernier, WeWork avait d\u00e9j\u00e0 exprim\u00e9 des &#8220;doutes substantiels&#8221; sur la viabilit\u00e9 de son activit\u00e9 et a depuis subi plusieurs chutes \u00e0 la Bourse de New York. La derni\u00e8re en date remonte \u00e0 novembre,<strong> lorsque les actions du g\u00e9ant du coworking ont plong\u00e9 de plus de 50%, \u00e0 1,10$ par action<\/strong>, apr\u00e8s que le Wall Street Journal a rapport\u00e9 que l&#8217;entreprise pr\u00e9voyait de d\u00e9poser son bilan de mani\u00e8re imminente.<\/p>\n<p><strong>WeWork est entr\u00e9 en bourse en 2021 \u00e0 la suite d&#8217;une fusion avec la soci\u00e9t\u00e9 d&#8217;acquisition \u00e0 but sp\u00e9cial (Spac) BowX Acquisition.<\/strong> La multinationale fond\u00e9e par Adam Neumann a d\u00e9j\u00e0 \u00e9t\u00e9 \u00e9valu\u00e9e \u00e0 50 milliards de dollars.<\/p>\n<p>Lors de sa 1<sup>re <\/sup>tentative d&#8217;introduction en bourse, la valorisation de l&#8217;entreprise a chut\u00e9<strong> lorsque les documents relatifs \u00e0 l&#8217;introduction en bourse ont r\u00e9v\u00e9l\u00e9 une perte de 1,9 milliard de dollars et que l&#8217;entreprise \u00e9tait sur le point d&#8217;\u00e9puiser ses liquidit\u00e9s restantes. <\/strong>Pendant la crise de WeWork, qui a conduit au d\u00e9part de son fondateur Adam Neuman, le groupe japonais Softbank est devenu le principal actionnaire de l&#8217;entreprise.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Swiss Life vient de lancer la 1re grande transaction de bureaux de l&#8217;ann\u00e9e, la vente de l&#8217;immeuble situ\u00e9 au 27 rue Eloy Gonzalo, si\u00e8ge de la soci\u00e9t\u00e9 de location de bureaux flexibles WeWork \u00e0 Chamber\u00ed. WeWork continue de supprimer des postes. La soci\u00e9t\u00e9 new-yorkaise de location de bureaux flexibles, autrefois \u00e9valu\u00e9e \u00e0 50 milliards de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":21446,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[734,375,735,736],"class_list":["post-70595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-chamberi","tag-madrid","tag-swiss-life","tag-wework"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/70595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=70595"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/70595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/21446"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=70595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=70595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=70595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}