{"id":71045,"date":"2026-03-12T00:04:10","date_gmt":"2026-03-12T00:04:10","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2026\/03\/12\/hotelbeds-pourrait-entrer-en-bourse-avec-une-capitalisation-boursiere-de-5-milliards-deuros-2\/"},"modified":"2026-05-08T03:54:07","modified_gmt":"2026-05-08T03:54:07","slug":"hotelbeds-pourrait-entrer-en-bourse-avec-une-capitalisation-boursiere-de-5-milliards-deuros-2","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2026\/03\/12\/hotelbeds-pourrait-entrer-en-bourse-avec-une-capitalisation-boursiere-de-5-milliards-deuros-2\/","title":{"rendered":"Hotelbeds pourrait entrer en bourse avec une capitalisation boursi\u00e8re de 5 milliards d&#8217;euros"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p>La plateforme de distribution d&#8217;h\u00e9bergements en gros Hotelbeds pr\u00e9pare actuellement son introduction en bourse, par le biais d&#8217;une offre publique initiale (IPO), gr\u00e2ce \u00e0 laquelle elle pourrait atteindre une capitalisation de 5 milliards d&#8217;euros. HOSTELTUR avait d\u00e9j\u00e0 \u00e9voqu\u00e9 en juin la <strong>possibilit\u00e9 de r\u00e9aliser cette op\u00e9ration<\/strong>, en vue d&#8217;une vente ult\u00e9rieure de l&#8217;entreprise.<\/p>\n<p>Selon Expansi\u00f3n, les propri\u00e9taires de la soci\u00e9t\u00e9 bas\u00e9e \u00e0 Majorque, Cinven et CPPIB, ont engag\u00e9 Morgan Stanley et Evercore comme conseillers pour les aider \u00e0 d\u00e9terminer les chances de succ\u00e8s de l&#8217;introduction en bourse sur le march\u00e9 espagnol. Aucun autre d\u00e9tail de cette op\u00e9ration boursi\u00e8re n&#8217;a \u00e9t\u00e9 divulgu\u00e9 \u00e0 ce stade.<\/p>\n<p>En effet, \u00e0 la fin du mois de mars, on a appris que <strong>3 fonds d&#8217;investissement priv\u00e9s<\/strong>, Cinven, EQT et Canada Pension Plan Investment, \u00e9taient \u00e0 l&#8217;\u00e9coute d&#8217;offres pour la plus grande banque de lits du monde, comme l&#8217;a publi\u00e9 HOSTELTUR dans <em>Hotelbeds for sale for 3 billion euros ?<\/em> \u00c0 l&#8217;\u00e9poque, il avait \u00e9t\u00e9 rapport\u00e9 que la propri\u00e9t\u00e9 cherchait \u00e0 se d\u00e9sinvestir par le biais d&#8217;une introduction en bourse ou d&#8217;une vente pure et simple.<\/p>\n<h3 class=\"wp-block-heading\"><strong>La bonne dynamique d&#8217;Hotelbeds<\/strong><\/h3>\n<p>Il faut dire que depuis le d\u00e9but de l&#8217;ann\u00e9e 2023, l&#8217;activit\u00e9 B2B d&#8217;Hotelbeds a connu une &#8220;<strong>reprise<\/strong> <strong>significative<\/strong>&#8221; de la demande. \u00c0 tel point qu&#8217;entre le 9 et le 22 janvier, la marque a connu la meilleure quinzaine de r\u00e9servations par chiffre d&#8217;affaires de son histoire, avec une r\u00e9servation par seconde en p\u00e9riode de pointe.<\/p>\n<p>Hotelbeds re\u00e7oit 4 milliards de demandes de recherche par jour, contre 9 milliards pour Google.<\/p>\n<p>Hotelbeds est une soci\u00e9t\u00e9 de technologie de voyage bas\u00e9e \u00e0 Palma, fond\u00e9e en 2001 au sein de Viajes Barcel\u00f3, qui est devenue l&#8217;une des plus grandes banques de lits au monde, offrant 320.000 produits de voyage dans plus de 195 pays, y compris 300.000 h\u00f4tels.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La plateforme de distribution d&#8217;h\u00e9bergements en gros Hotelbeds pr\u00e9pare actuellement son introduction en bourse, par le biais d&#8217;une offre publique initiale (IPO), gr\u00e2ce \u00e0 laquelle elle pourrait atteindre une capitalisation de 5 milliards d&#8217;euros. HOSTELTUR avait d\u00e9j\u00e0 \u00e9voqu\u00e9 en juin la possibilit\u00e9 de r\u00e9aliser cette op\u00e9ration, en vue d&#8217;une vente ult\u00e9rieure de l&#8217;entreprise. Selon Expansi\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":22697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212,258],"tags":[],"class_list":["post-71045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-hotels-living"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/71045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=71045"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/71045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/22697"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=71045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=71045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=71045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}