{"id":72257,"date":"2026-03-14T15:52:59","date_gmt":"2026-03-14T15:52:59","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2026\/03\/14\/redevco-investit-80-millions-dans-lachat-de-six-hotels-en-espagne-et-au-portugal-2\/"},"modified":"2026-05-09T18:18:04","modified_gmt":"2026-05-09T18:18:04","slug":"redevco-investit-80-millions-dans-lachat-de-six-hotels-en-espagne-et-au-portugal-2","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2026\/03\/14\/redevco-investit-80-millions-dans-lachat-de-six-hotels-en-espagne-et-au-portugal-2\/","title":{"rendered":"Redevco investit 80 millions dans l&#8217;achat de six h\u00f4tels en Espagne et au Portugal"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p>Le fonds n\u00e9erlandais transformera des propri\u00e9t\u00e9s en h\u00f4tels-boutiques aux mains d&#8217;op\u00e9rateurs sp\u00e9cialis\u00e9s. Le march\u00e9 ib\u00e9rique deviendra un laboratoire avant de lancer un fonds paneurop\u00e9en de 500 \u00e0 700 millions.<\/p>\n<p>Investissement h\u00f4telier de Redevco Redevco entre dans le segment h\u00f4telier en Espagne et au Portugal. Le fonds n\u00e9erlandais a achet\u00e9 six actifs en Espagne et au Portugal pour plus de 80 millions d&#8217;euros, comme annonc\u00e9 dans un communiqu\u00e9. <\/p>\n<p>Les investissements \u00e0 Lisbonne, Bilbao, S\u00e9ville, Porto et Malaga serviront de base au lancement de la plateforme de joint-venture Next Gen Stays de Redevco, qui transformera les propri\u00e9t\u00e9s en h\u00f4tels-boutiques. Les plans du fonds sont de construire un portefeuille de 250 millions d&#8217;euros sur les march\u00e9s ib\u00e9riques avec des op\u00e9rateurs sp\u00e9cialis\u00e9s, avant de se d\u00e9velopper en un v\u00e9hicule h\u00f4telier paneurop\u00e9en avec un objectif de volume d&#8217;investissement compris entre 500 et 700 millions d&#8217;euros. <\/p>\n<p>L&#8217;objectif de la strat\u00e9gie est d&#8217;exploiter la r\u00e9surgence et la croissance post-pand\u00e9mique du march\u00e9 du tourisme et de l&#8217;exp\u00e9rience des jeunes et d&#8217;ajouter un portefeuille g\u00e9r\u00e9 par des professionnels dans un secteur en \u00e9volution et en expansion rapides, selon le fonds. Les h\u00f4tels acquis dans le cadre de ce premier investissement sont situ\u00e9s \u00e0 Lisbonne, Bilbao, S\u00e9ville, Porto et Malaga.<\/p>\n<p>&#8220;En combinant la solide exp\u00e9rience de Redevco en mati\u00e8re d&#8217;investissements immobiliers dans le secteur du commerce de d\u00e9tail et de r\u00e9g\u00e9n\u00e9ration urbaine avec les meilleurs op\u00e9rateurs h\u00f4teliers, notre strat\u00e9gie Next Gen Stays s&#8217;ajuste aux derni\u00e8res tendances en mati\u00e8re de voyage et de consommation \u00bb, explique Israel Casanova, directeur g\u00e9n\u00e9ral de la gestion des transactions mondiales du fonds. D&#8217;autre part, Redevco n\u00e9gocie l&#8217;achat du centre El Corte Ingl\u00e9s \u00e0 Portal de l&#8217;\u00c0ngel \u00e0 Barcelone, une op\u00e9ration qui pourrait \u00eatre ferm\u00e9e dans les prochaines semaines. La transaction sera d&#8217;environ 190 millions d&#8217;euros.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fonds n\u00e9erlandais transformera des propri\u00e9t\u00e9s en h\u00f4tels-boutiques aux mains d&#8217;op\u00e9rateurs sp\u00e9cialis\u00e9s. Le march\u00e9 ib\u00e9rique deviendra un laboratoire avant de lancer un fonds paneurop\u00e9en de 500 \u00e0 700 millions. Investissement h\u00f4telier de Redevco Redevco entre dans le segment h\u00f4telier en Espagne et au Portugal. Le fonds n\u00e9erlandais a achet\u00e9 six actifs en Espagne et au [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":26020,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-72257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/72257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=72257"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/72257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media\/26020"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=72257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=72257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=72257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}