{"id":83741,"date":"2026-03-14T16:40:05","date_gmt":"2026-03-14T16:40:05","guid":{"rendered":"https:\/\/yo.estate\/index.php\/2026\/03\/14\/les-foires-espagnoles-sattendent-a-une-reprise-complete-en-2023-3\/"},"modified":"2026-03-14T16:40:05","modified_gmt":"2026-03-14T16:40:05","slug":"les-foires-espagnoles-sattendent-a-une-reprise-complete-en-2023-3-2","status":"publish","type":"post","link":"https:\/\/yo.estate\/index.php\/2026\/03\/14\/les-foires-espagnoles-sattendent-a-une-reprise-complete-en-2023-3-2\/","title":{"rendered":"Les foires espagnoles s&#8217;attendent \u00e0 une reprise compl\u00e8te en 2023"},"content":{"rendered":"<p>Le groupe suisse Pictet rach\u00e8te l&#8217;Expo Hotel Valencia pour 30 millions d&#8217;euros<\/p>\n<p>L&#8217;Expo Hotel Valencia sera r\u00e9nov\u00e9 et exploit\u00e9 avec une marque internationale<\/p>\n<p>29 septembre 2022<br \/>Pictet Alternative Advisors a achet\u00e9 le Kimpton Aysla Mallorca de 79 chambres en mars L&#8217;achat par Pictet fait partie de sa strat\u00e9gie de repositionnement d&#8217;actifs L&#8217;Expo Hotel Valencia sera r\u00e9nov\u00e9, \u00e9levant sa cat\u00e9gorie \u00e0 4 \u00e9toiles, et aura un op\u00e9rateur international<br \/>Les fonds g\u00e9r\u00e9s par Pictet Alternative Advisors ont achet\u00e9 l&#8217;Expo Hotel Valencia, qui \u00e9tait l&#8217;un des actifs les plus repr\u00e9sentatifs du groupe Selenta. Des sources proches de l&#8217;op\u00e9ration ont confirm\u00e9 \u00e0 HOSTELTUR que la vente de l&#8217;actif \u00ab s&#8217;est faite au nom des propri\u00e9taires directs, la famille Mestre \u00bb. Bien que le montant et les modalit\u00e9s de la transaction n&#8217;aient pas \u00e9t\u00e9 confirm\u00e9s, ils l&#8217;estiment \u00e0 environ 30 millions d&#8217;euros.<br \/>Img Hosteltur<br \/>En juillet de l&#8217;ann\u00e9e derni\u00e8re, la famille Mestre a vendu quatre actifs h\u00f4teliers Selenta, \u00e0 l&#8217;exception de l&#8217;Expo Hotel Valencia, comme expliqu\u00e9 dans la cha\u00eene The Selenta Group, vendu pour 440 millions d&#8217;euros. Et ce jeudi, la vente de l&#8217;h\u00f4tel 3 \u00e9toiles a \u00e9t\u00e9 confirm\u00e9e, situ\u00e9 dans l&#8217;une des principales art\u00e8res de Valence, juste en face de l&#8217;Alameda \u00e0 c\u00f4t\u00e9 des jardins du T\u00faria.<br \/>CBRE a conseill\u00e9 l&#8217;acquisition et la recherche de financement de l&#8217;h\u00f4tel avec Ur\u00eda Men\u00e9ndez et P\u00e9rez Llorca.<\/p>\n<p>L&#8217;h\u00f4tel dispose de 377 chambres, d&#8217;un restaurant, d&#8217;un bar, d&#8217;une piscine ext\u00e9rieure, d&#8217;une terrasse et de plus de 1 500 m\u00e8tres carr\u00e9s pour les r\u00e9unions et les \u00e9v\u00e9nements. Apr\u00e8s sa r\u00e9forme, il passera \u00e0 la cat\u00e9gorie des 4 \u00e9toiles, ont-ils confirm\u00e9 \u00e0 HOSTELTUR.<br \/>L&#8217;h\u00f4tel fera l&#8217;objet d&#8217;une r\u00e9forme compl\u00e8te, selon des crit\u00e8res de durabilit\u00e9 et sera exploit\u00e9 sous une marque internationale, selon Pablo Granell, directeur immobilier de Pictet Alternative Advisors pour l&#8217;Espagne.<br \/>Pictet Alternative Advisors a r\u00e9alis\u00e9 plusieurs op\u00e9rations immobili\u00e8res en Espagne depuis le d\u00e9but de l&#8217;ann\u00e9e, dont l&#8217;acquisition de l&#8217;h\u00f4tel Kimpton Aysla Mallorca, un h\u00f4tel 5 \u00e9toiles situ\u00e9 \u00e0 Calvi\u00e1 (Majorque) et g\u00e9r\u00e9 par Intercontinental Hotels Group (IHG) sous sa marque de luxe marque lifestyle Kimpton Hotels &amp; Restaurants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe suisse Pictet rach\u00e8te l&#8217;Expo Hotel Valencia pour 30 millions d&#8217;euros L&#8217;Expo Hotel Valencia sera r\u00e9nov\u00e9 et exploit\u00e9 avec une marque internationale 29 septembre 2022Pictet Alternative Advisors a achet\u00e9 le Kimpton Aysla Mallorca de 79 chambres en mars L&#8217;achat par Pictet fait partie de sa strat\u00e9gie de repositionnement d&#8217;actifs L&#8217;Expo Hotel Valencia sera r\u00e9nov\u00e9, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212,5667],"tags":[],"class_list":["post-83741","post","type-post","status-publish","format-standard","hentry","category-breaking-news","category-networking"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/83741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/comments?post=83741"}],"version-history":[{"count":0,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/posts\/83741\/revisions"}],"wp:attachment":[{"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/media?parent=83741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/categories?post=83741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yo.estate\/index.php\/wp-json\/wp\/v2\/tags?post=83741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}